{"id":597,"date":"2017-10-06T19:31:31","date_gmt":"2017-10-06T18:31:31","guid":{"rendered":"https:\/\/www.dolidon-partners.com\/professionnels\/lee-neumann\/"},"modified":"2026-04-14T13:42:09","modified_gmt":"2026-04-14T12:42:09","slug":"lee-neumann","status":"publish","type":"page","link":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/","title":{"rendered":"Lee Neumann"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":585,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"template-person.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-597","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lee Neumann - Law Firm | Dolidon Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lee Neumann\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/\" \/>\n<meta property=\"og:site_name\" content=\"Dolidon Partners | Soci\u00e9t\u00e9 d&#039;avocats\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dolidonpartners\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T12:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dolidon-partners.com\/wp-content\/uploads\/capture-decran-2017-10-23-a-17-28-51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1437\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/lee-neumann\\\/\",\"url\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/lee-neumann\\\/\",\"name\":\"Lee Neumann - Law Firm | Dolidon Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#website\"},\"datePublished\":\"2017-10-06T18:31:31+00:00\",\"dateModified\":\"2026-04-14T12:42:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/lee-neumann\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/lee-neumann\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/lee-neumann\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professionnels\",\"item\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lee Neumann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/\",\"name\":\"Dolidon Partners | Soci\u00e9t\u00e9 d&#039;avocats\",\"description\":\"Avocats d\u00e9di\u00e9s aux pratiques cl\u00e9s du Droit des Affaires, nous aidons nos clients \u00e0 d\u00e9finir et \u00e0 r\u00e9aliser leurs objectifs.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#organization\",\"name\":\"Dolidon Partners\",\"url\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dolidon-partners.com\\\/wp-content\\\/uploads\\\/dp-logos-autrecarre-noir-bd.png\",\"contentUrl\":\"https:\\\/\\\/www.dolidon-partners.com\\\/wp-content\\\/uploads\\\/dp-logos-autrecarre-noir-bd.png\",\"width\":143,\"height\":142,\"caption\":\"Dolidon Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dolidon-partners.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dolidonpartners\",\"https:\\\/\\\/www.instagram.com\\\/dolidonpartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dolidon-partners\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lee Neumann - Law Firm | Dolidon Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/","og_locale":"en_US","og_type":"article","og_title":"Lee Neumann","og_url":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/","og_site_name":"Dolidon Partners | Soci\u00e9t\u00e9 d&#039;avocats","article_publisher":"https:\/\/www.facebook.com\/dolidonpartners","article_modified_time":"2026-04-14T12:42:09+00:00","og_image":[{"width":1437,"height":1076,"url":"https:\/\/www.dolidon-partners.com\/wp-content\/uploads\/capture-decran-2017-10-23-a-17-28-51.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/","url":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/","name":"Lee Neumann - Law Firm | Dolidon Partners","isPartOf":{"@id":"https:\/\/www.dolidon-partners.com\/en\/#website"},"datePublished":"2017-10-06T18:31:31+00:00","dateModified":"2026-04-14T12:42:09+00:00","breadcrumb":{"@id":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dolidon-partners.com\/en\/team\/lee-neumann\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dolidon-partners.com\/en\/"},{"@type":"ListItem","position":2,"name":"Professionnels","item":"https:\/\/www.dolidon-partners.com\/en\/team\/"},{"@type":"ListItem","position":3,"name":"Lee Neumann"}]},{"@type":"WebSite","@id":"https:\/\/www.dolidon-partners.com\/en\/#website","url":"https:\/\/www.dolidon-partners.com\/en\/","name":"Dolidon Partners | Soci\u00e9t\u00e9 d&#039;avocats","description":"Avocats d\u00e9di\u00e9s aux pratiques cl\u00e9s du Droit des Affaires, nous aidons nos clients \u00e0 d\u00e9finir et \u00e0 r\u00e9aliser leurs objectifs.","publisher":{"@id":"https:\/\/www.dolidon-partners.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dolidon-partners.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dolidon-partners.com\/en\/#organization","name":"Dolidon Partners","url":"https:\/\/www.dolidon-partners.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dolidon-partners.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.dolidon-partners.com\/wp-content\/uploads\/dp-logos-autrecarre-noir-bd.png","contentUrl":"https:\/\/www.dolidon-partners.com\/wp-content\/uploads\/dp-logos-autrecarre-noir-bd.png","width":143,"height":142,"caption":"Dolidon Partners"},"image":{"@id":"https:\/\/www.dolidon-partners.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dolidonpartners","https:\/\/www.instagram.com\/dolidonpartners","https:\/\/www.linkedin.com\/company\/dolidon-partners"]}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/pages\/597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/comments?post=597"}],"version-history":[{"count":1,"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/pages\/597\/revisions"}],"predecessor-version":[{"id":749,"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/pages\/597\/revisions\/749"}],"up":[{"embeddable":true,"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/pages\/585"}],"wp:attachment":[{"href":"https:\/\/www.dolidon-partners.com\/en\/wp-json\/wp\/v2\/media?parent=597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}